{"id":144,"count":1,"description":"","link":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/tag\/paleobiologia\/","name":"paleobiolog\u00eda","slug":"paleobiologia","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/tags\/144"}],"collection":[{"href":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts?tags=144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}