{"id":11,"count":15,"description":"","link":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/tag\/astronomia\/","name":"Astronom\u00eda","slug":"astronomia","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/tags\/11"}],"collection":[{"href":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts?tags=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}