{"id":5266,"date":"2023-07-10T11:45:55","date_gmt":"2023-07-10T14:45:55","guid":{"rendered":"https:\/\/desdelapatagonia.uncoma.edu.ar\/?p=5266"},"modified":"2023-07-11T10:55:04","modified_gmt":"2023-07-11T13:55:04","slug":"el-meteorito-caperr","status":"publish","type":"post","link":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/el-meteorito-caperr\/","title":{"rendered":"EL METEORITO C\u00c1PERR"},"content":{"rendered":"\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center aligncenter has-white-background-color has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/desdelapatagonia.uncoma.edu.ar\/wp-content\/uploads\/2023\/07\/GiraudoLucio_Figura-9_sin_texto.jpg\" alt=\"\" class=\"wp-image-5267\" width=\"322\" height=\"214\" srcset=\"https:\/\/desdelapatagonia.uncoma.edu.ar\/wp-content\/uploads\/2023\/07\/GiraudoLucio_Figura-9_sin_texto.jpg 734w, https:\/\/desdelapatagonia.uncoma.edu.ar\/wp-content\/uploads\/2023\/07\/GiraudoLucio_Figura-9_sin_texto-300x200.jpg 300w, https:\/\/desdelapatagonia.uncoma.edu.ar\/wp-content\/uploads\/2023\/07\/GiraudoLucio_Figura-9_sin_texto-404x270.jpg 404w\" sizes=\"(max-width: 322px) 100vw, 322px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:30%\"><\/div>\n<\/div>\n\n\n\n<h4 class=\"has-text-align-center wp-block-heading\">Isabel Giraudo de Lucio<strong>\u00b9 <\/strong><\/h4>\n\n\n\n<p>El meteorito met\u00e1lico C\u00e1perr cay\u00f3 en tiempos prehist\u00f3ricos en la provincia de Chubut, y su ca\u00edda fue presenciada por nativos aonikenk. Ellos lo preservaron con veneraci\u00f3n y relataron su ca\u00edda a trav\u00e9s de un mito, modelado con dimensiones po\u00e9ticas, simb\u00f3licas y antropog\u00f3nicas. Los meteoritos met\u00e1licos son remanentes de n\u00facleos de protoplanetas que se formaron y desintegraron en el Sistema Solar temprano. Su composici\u00f3n y estructura interna son de enorme inter\u00e9s para la ciencia planetaria. Desde 1896, el meteorito C\u00e1perr forma parte de las colecciones del Museo de Ciencias Naturales de La Plata, por decisi\u00f3n de su director y fundador, el perito Francisco P. Moreno.<\/p>\n\n\n\n<p><strong>Palabras clave<\/strong>: <em>aonikenk<\/em>, mito, octaedrita, siderito, Taamta.<br><strong>Keywords<\/strong>:  <em>aonikenk<\/em>, myth, octahedrite, siderite, Taamta.<\/p>\n\n\n\n<p>\u00b9 Museo de Piedras Patag\u00f3nicas. Mall\u00edn Ahogado, Ruta Provincial 86, El Bols\u00f3n, R\u00edo Negro.<\/p>\n\n\n\n<p>Recibido:  18\/09\/22. Aceptado: 20\/03\/23.<\/p>\n\n\n\n<p>Contacto: <a href=\"mailto:piedrasdepatagonia@gmail.com\">piedrasdepatagonia@gmail.com<\/a><\/p>\n\n\n\n<p>Modo de citar este art\u00edculo: Giraudo de Lucio, I. (2023). El meteorito C\u00e1perr.&nbsp;Desde La Patagonia. Difundiendo Saberes,&nbsp;20(35), 2\u20138.<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\"><a href=\"http:\/\/id.caicyt.gov.ar\/ark:\/s26185385\/etm6gkzqz\" data-type=\"URL\" data-id=\"http:\/\/id.caicyt.gov.ar\/ark:\/s26185385\/etm6gkzqz\">ark:\/s26185385\/db09bcos8<\/a><\/mark><\/strong><\/code><\/pre>\n\n\n\n<h4 style=\"text-align: right;\"><a href=\"https:\/\/desdelapatagonia.uncoma.edu.ar\/wp-content\/uploads\/2023\/07\/Revista-35_Giraudo-de-Lucio.pdf\"><span style=\"color: #3366ff;\">Leer&nbsp;art\u00edculo completo&nbsp;&nbsp;&nbsp;&nbsp;<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-221 size-full\" src=\"https:\/\/desdelapatagonia.uncoma.edu.ar\/wp-content\/uploads\/2016\/06\/pdf_imagen.jpg\" alt=\"\" width=\"37\" height=\"37\"><\/span><\/a><\/h4>\n\r\n","protected":false},"excerpt":{"rendered":"<p>Isabel Giraudo de Lucio\u00b9 El meteorito met\u00e1lico C\u00e1perr cay\u00f3 en tiempos prehist\u00f3ricos en la provincia de Chubut, y su ca\u00edda fue presenciada por nativos aonikenk. Ellos lo preservaron con veneraci\u00f3n y relataron su ca\u00edda a trav\u00e9s de un mito, modelado con dimensiones po\u00e9ticas, simb\u00f3licas y antropog\u00f3nicas. Los meteoritos met\u00e1licos son remanentes de n\u00facleos de protoplanetas que se formaron y desintegraron en el Sistema Solar temprano. Su composici\u00f3n y estructura interna son de enorme inter\u00e9s para la ciencia planetaria. Desde 1896,&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/el-meteorito-caperr\/\"> Read More<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1271],"tags":[11,31,39],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/5266"}],"collection":[{"href":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=5266"}],"version-history":[{"count":20,"href":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/5266\/revisions"}],"predecessor-version":[{"id":5318,"href":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/5266\/revisions\/5318"}],"wp:attachment":[{"href":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=5266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=5266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desdelapatagonia.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=5266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}